{"id":845,"date":"2009-06-20T20:45:30","date_gmt":"2009-06-20T18:45:30","guid":{"rendered":"http:\/\/www.ff-muehldorf.at\/?p=845"},"modified":"2015-08-14T21:36:09","modified_gmt":"2015-08-14T19:36:09","slug":"dorffest-freudenstein","status":"publish","type":"post","link":"https:\/\/ff-muehldorf.at\/wordpress\/2009\/06\/20\/dorffest-freudenstein\/","title":{"rendered":"Dorffest Freudenstein"},"content":{"rendered":"<p>Am Wochenende vom 19.- 21. Juni 2009 war es wiedereinmal soweit. Unsere Feuerwehr veranstaltete wieder ein Dorffest in Freudenstein, das dieses Jahr erstmals an einem neuen Standort, direkt an der B131, durchgef\u00fchrt wurde. Dank unserer wetterfesten G\u00e4ste, konnte die Stimmung auch durch die anhaltenden Regenf\u00e4lle am Freitag nicht wirklich eingetr\u00fcbt werden. F\u00fcr Musik und Unterhaltung sorgte am Freitag die Band &#8222;Firstline&#8220;, am Samstag &#8222;Six-Pence&#8220; und am Sonntag der Musikverein Lacken. Nach den starken Regenf\u00e4llen am Freitag blieb es am Samstag Abend relativ Trocken. Zum Fr\u00fchschoppen am Sonntag kamen sogar die ersten Sonnenstrahlen wieder zum Vorschein. Wir die Freiwillige Feuerwehr M\u00fchldorf m\u00f6chten uns auf diesem Weg nochmals bei allen G\u00e4sten f\u00fcr ihr Kommen bedanken und w\u00fcrden uns auch \u00fcber einen Besuch im n\u00e4chsten Jahr sehr freuen.<\/p>\n<p><strong>Weitere Fotos vom Fest findet ihr in der Fotogalerie:<\/strong><br \/>\n<a href=\".\/simpleviewer\/index.php?album=Dorffest-2009\" target=\"_blank\">Fotos vom Dorffest 2009<\/a><br \/>\n<a href=\"http:\/\/dorffest.ff-muehldorf.at\" target=\"_blank\">Dorffest 2009 Webseite<\/a><\/p>\n<p><strong>Fotos:<\/strong><br \/>\n<div id=\"kad-wp-gallery745\" class=\"kad-wp-gallery gallery kt-gallery-column-6 init-isotope-intrinsic reinit-isotope kad-light-wp-gallery clearfix rowtight\" data-fade-in=\"1\" data-iso-selector=\".g_item\" data-iso-style=\"masonry\" data-iso-filter=\"false\"><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_3.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:75%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_3-240x180.jpg\" srcset=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_3-240x180.jpg 240w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_3-300x225.jpg 300w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_3-1024x768.jpg 1024w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_3-480x360.jpg 480w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_3.jpg 1200w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_3-240x180.jpg\"><meta itemprop=\"width\" content=\"240px\"><meta itemprop=\"height\" content=\"180px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_4.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:75%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_4-240x180.jpg\" srcset=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_4-240x180.jpg 240w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_4-300x225.jpg 300w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_4-1024x768.jpg 1024w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_4-480x360.jpg 480w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_4.jpg 1200w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_4-240x180.jpg\"><meta itemprop=\"width\" content=\"240px\"><meta itemprop=\"height\" content=\"180px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_5.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:75%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_5-240x180.jpg\" srcset=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_5-240x180.jpg 240w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_5-300x225.jpg 300w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_5-1024x768.jpg 1024w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_5-480x360.jpg 480w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_5.jpg 1200w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_5-240x180.jpg\"><meta itemprop=\"width\" content=\"240px\"><meta itemprop=\"height\" content=\"180px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_6.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:75%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_6-240x180.jpg\" srcset=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_6-240x180.jpg 240w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_6-300x225.jpg 300w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_6-1024x768.jpg 1024w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_6-480x360.jpg 480w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_6.jpg 1200w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_6-240x180.jpg\"><meta itemprop=\"width\" content=\"240px\"><meta itemprop=\"height\" content=\"180px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_1.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:75%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_1-240x180.jpg\" srcset=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_1-240x180.jpg 240w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_1-300x225.jpg 300w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_1-1024x768.jpg 1024w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_1-480x360.jpg 480w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_1.jpg 1200w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_1-240x180.jpg\"><meta itemprop=\"width\" content=\"240px\"><meta itemprop=\"height\" content=\"180px\"><\/div><\/div><\/a><\/div><\/div><div class=\"tcol-lg-2 tcol-md-2 tcol-sm-3 tcol-xs-4 tcol-ss-6 g_item\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item\"><a href=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_2.jpg\" data-rel=\"lightbox\" class=\"lightboxhover\"><div class=\"kt-intrinsic\" style=\"padding-bottom:75%;\"><div itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_2-240x180.jpg\" srcset=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_2-240x180.jpg 240w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_2-300x225.jpg 300w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_2-1024x768.jpg 1024w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_2-480x360.jpg 480w, https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_2.jpg 1200w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" data-caption=\"\" class=\"light-dropshaddow\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/ff-muehldorf.at\/wordpress\/wp-content\/uploads\/2009\/06\/20\/2009-06-20_Dorffest-Freudenstein_2-240x180.jpg\"><meta itemprop=\"width\" content=\"240px\"><meta itemprop=\"height\" content=\"180px\"><\/div><\/div><\/a><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Am Wochenende vom 19.- 21. Juni 2009 war es wiedereinmal soweit. Unsere Feuerwehr veranstaltete wieder ein Dorffest in Freudenstein, das dieses Jahr erstmals an einem neuen Standort, direkt an der B131, durchgef\u00fchrt wurde. Dank unserer wetterfesten G\u00e4ste, konnte die Stimmung &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/ff-muehldorf.at\/wordpress\/2009\/06\/20\/dorffest-freudenstein\/\" aria-label=\"Dorffest Freudenstein\">weiter&#8230;<\/a><\/p>\n","protected":false},"author":7,"featured_media":847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,66],"tags":[155,202,203,156],"class_list":["post-845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktivitaeten","category-veranstaltungen","tag-b131","tag-dorffest","tag-fest","tag-freudenstein"],"_links":{"self":[{"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/posts\/845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/comments?post=845"}],"version-history":[{"count":2,"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/posts\/845\/revisions"}],"predecessor-version":[{"id":854,"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/posts\/845\/revisions\/854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/media\/847"}],"wp:attachment":[{"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/media?parent=845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/categories?post=845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ff-muehldorf.at\/wordpress\/wp-json\/wp\/v2\/tags?post=845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}